{"id":4190,"date":"2023-10-27T07:18:22","date_gmt":"2023-10-27T07:18:22","guid":{"rendered":"https:\/\/swforming.com\/?p=4190"},"modified":"2023-10-27T07:18:24","modified_gmt":"2023-10-27T07:18:24","slug":"ag-classic-rib-roof-roll-forming-machine","status":"publish","type":"post","link":"https:\/\/swforming.com\/fr\/ag-classic-rib-roof-roll-forming-machine\/","title":{"rendered":"Machine de formage de toits \u00e0 nervures Ag Classic"},"content":{"rendered":"<p class=\"wp-block-paragraph\">La <a href=\"https:\/\/swforming.com\/fr\/produit\/\">Machine de profilage de toits \u00e0 nervures classiques ag<\/a> est un \u00e9quipement essentiel pour la fabrication efficace de panneaux de toiture m\u00e9talliques nervur\u00e9s et de feuilles de platelage. Ce guide fournit un aper\u00e7u complet des profileuses de toiture \u00e0 nervures classiques, de leur fonctionnement, de leurs types, de leurs applications, de leurs sp\u00e9cifications, de leurs fournisseurs, de leur installation, de leur fonctionnement, de leur entretien et de leurs crit\u00e8res de s\u00e9lection.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Aper\u00e7u de la profileuse de toits \u00e0 nervures Ag Classic<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">La <a href=\"https:\/\/swforming.com\/fr\/produit\/\">Machine de profilage de toits \u00e0 nervures classiques ag<\/a> est utilis\u00e9e pour former des bobines de m\u00e9tal en panneaux de toiture et en feuilles avec des profils nervur\u00e9s ou ondul\u00e9s. Ces machines utilisent une s\u00e9rie de matrices \u00e0 rouleaux pour plier et fa\u00e7onner la t\u00f4le dans les formes de nervures souhait\u00e9es au fur et \u00e0 mesure qu'elle passe par les diff\u00e9rents postes de formage.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Quelques caract\u00e9ristiques cl\u00e9s des profileurs de toits \u00e0 nervures ag classiques :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Efficacit\u00e9 de production \u00e9lev\u00e9e et vitesses jusqu'\u00e0 25 m\/min<\/li>\n\n\n\n<li>Possibilit\u00e9 de produire diff\u00e9rents profils et hauteurs de nervures<\/li>\n\n\n\n<li>La conception du changement rapide de rouleau permet de changer rapidement de profil<\/li>\n\n\n\n<li>Construction robuste tout acier soud\u00e9 pour une meilleure durabilit\u00e9<\/li>\n\n\n\n<li>Syst\u00e8me de contr\u00f4le PLC avanc\u00e9 pour la pr\u00e9cision et l'automatisation<\/li>\n\n\n\n<li>Dispositifs de s\u00e9curit\u00e9 tels que l'\u00e9quipement de guidage de la feuille et les protections<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">Principaux \u00e9l\u00e9ments<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Les principaux composants d'une machine de formage de toits \u00e0 nervures ag classique sont les suivants :<\/p>\n\n\n\n<figure class=\"wp-block-table\"><table><thead><tr><th>Composant<\/th><th>Description<\/th><\/tr><\/thead><tbody><tr><td>D\u00e9rouleur<\/td><td>Maintient la bobine de m\u00e9tal et l'introduit dans la profileuse<\/td><\/tr><tr><td>Alimentateur<\/td><td>Introduit la t\u00f4le dans les stations de formage \u00e0 la vitesse programm\u00e9e<\/td><\/tr><tr><td>Stations de formage<\/td><td>Chaque station forme progressivement la forme de la c\u00f4te<\/td><\/tr><tr><td>Unit\u00e9 de poin\u00e7onnage<\/td><td>Perfore les trous si n\u00e9cessaire<\/td><\/tr><tr><td>Syst\u00e8me hydraulique<\/td><td>Fournit de l'\u00e9nergie pour les op\u00e9rations de formage<\/td><\/tr><tr><td>Syst\u00e8me de contr\u00f4le<\/td><td>PLC et HMI pour le contr\u00f4le et la surveillance de la machine<\/td><\/tr><tr><td>Syst\u00e8me de changement de rouleaux<\/td><td>Permet un changement rapide de la matrice de roulage pour le changement de profil<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">Principe de fonctionnement<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Le principe de fonctionnement est le suivant :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Bobine de t\u00f4le charg\u00e9e sur le d\u00e9vidoir motoris\u00e9<\/li>\n\n\n\n<li>La feuille est introduite dans le chargeur \u00e0 une vitesse constante<\/li>\n\n\n\n<li>Les rouleaux de formage plient progressivement la feuille pour lui donner la forme nervur\u00e9e.<\/li>\n\n\n\n<li>L'unit\u00e9 de poin\u00e7onnage perfore les trous n\u00e9cessaires \u00e0 la fixation.<\/li>\n\n\n\n<li>La t\u00f4le ondul\u00e9e form\u00e9e est collect\u00e9e en continu \u00e0 la sortie.<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"607\" height=\"1024\" src=\"https:\/\/swforming.com\/wp-content\/uploads\/2023\/08\/Q20230828161824-607x1024.png\" alt=\"Machine de profilage de toits \u00e0 nervures classiques ag\" class=\"wp-image-3922\" title=\"\" srcset=\"\" sizes=\"(max-width: 607px) 100vw, 607px\" data-srcset=\"\" \/><figcaption><\/figcaption><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Types de machines \u00e0 former les toits \u00e0 nervures Ag Classic<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Les coffrages de toiture \u00e0 nervures Ag classic sont disponibles en diff\u00e9rents types, en fonction de la nature de la toiture et de l'utilisation qui en est faite :<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>1. Nombre d'ondulations :<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Machine \u00e0 c\u00f4te unique<\/li>\n\n\n\n<li>Machine \u00e0 double nervure<\/li>\n\n\n\n<li>Machine \u00e0 nervures multiples<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>2. Capacit\u00e9 de largeur de la t\u00f4le de couverture :<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Largeur \u00e9troite jusqu'\u00e0 800 mm<\/li>\n\n\n\n<li>Largeur standard jusqu'\u00e0 1250 mm<\/li>\n\n\n\n<li>Grande largeur jusqu'\u00e0 2100 mm<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>3. \u00c9paisseur de la t\u00f4le nervur\u00e9e :<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Calibre l\u00e9ger 0,35 - 0,8 mm<\/li>\n\n\n\n<li>Calibre normal 0,8 - 2,0 mm<\/li>\n\n\n\n<li>Jauge lourde sup\u00e9rieure \u00e0 2,0 mm<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>4. Niveau d'automatisation :<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Changement manuel de rouleau et de cliquetis<\/li>\n\n\n\n<li>Semi-automatique avec fonctions motoris\u00e9es<\/li>\n\n\n\n<li>Enti\u00e8rement automatique et contr\u00f4l\u00e9 par automate programmable (PLC)<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">Applications des machines \u00e0 former les toits \u00e0 nervures<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Les machines de formage de toits \u00e0 nervures Ag classic sont utilis\u00e9es pour la fabrication :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>T\u00f4les de couverture trap\u00e9zo\u00efdales<\/li>\n\n\n\n<li>T\u00f4les ondul\u00e9es pour toitures<\/li>\n\n\n\n<li>Platelage et t\u00f4les structurales<\/li>\n\n\n\n<li>Plaques de bardage<\/li>\n\n\n\n<li>Profils de panneaux muraux<\/li>\n\n\n\n<li>Feuilles de drainage de toiture<\/li>\n\n\n\n<li>Feuilles architecturales et d\u00e9coratives<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Ces produits de toiture m\u00e9tallique nervur\u00e9s sont largement utilis\u00e9s dans :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>B\u00e2timents industriels et commerciaux<\/li>\n\n\n\n<li>Entrep\u00f4ts et usines<\/li>\n\n\n\n<li>Toiture r\u00e9sidentielle<\/li>\n\n\n\n<li>B\u00e2timents \u00e0 structure m\u00e9tallique<\/li>\n\n\n\n<li>B\u00e2timents pr\u00e9fabriqu\u00e9s<\/li>\n\n\n\n<li>Hangars agricoles et d\u00e9pendances<\/li>\n\n\n\n<li>Drainage des toits et collecte des eaux de pluie<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">Sp\u00e9cifications techniques<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Les principales caract\u00e9ristiques techniques des formeurs de toits \u00e0 nervures ag classiques sont les suivantes :<\/p>\n\n\n\n<figure class=\"wp-block-table\"><table><thead><tr><th>Param\u00e8tres<\/th><th>Sp\u00e9cifications<\/th><\/tr><\/thead><tbody><tr><td>Largeur de la bobine Capacit\u00e9<\/td><td>800 mm \u00e0 2100 mm<\/td><\/tr><tr><td>\u00c9paisseur de la feuille<\/td><td>0,35 mm \u00e0 3 mm<\/td><\/tr><tr><td>Hauteur des nervures<\/td><td>15mm \u00e0 150mm<\/td><\/tr><tr><td>Vitesse de formage<\/td><td>8 - 25 m\/min<\/td><\/tr><tr><td>Nombre de stands<\/td><td>16 - 24 stands<\/td><\/tr><tr><td>Source de courant<\/td><td>380V ou 415V AC, 3 phases<\/td><\/tr><tr><td>Puissance du moteur<\/td><td>5,5kW \u00e0 11kW<\/td><\/tr><tr><td>Dimensions de la machine<\/td><td>8000mm x 1200mm x 2200mm<\/td><\/tr><tr><td>Poids de la machine<\/td><td>8000kg \u00e0 12000kg<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Conception et construction<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">La machine \u00e0 former les toits \u00e0 nervures ag classic a une construction enti\u00e8rement en acier et est con\u00e7ue pour des performances \u00e9lev\u00e9es :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Cadre<\/strong>&nbsp;- Fabriqu\u00e9 \u00e0 partir de plaques et de poutres d'acier soud\u00e9es, ce qui lui conf\u00e8re une grande rigidit\u00e9.<\/li>\n\n\n\n<li><strong>Bo\u00eetes \u00e0 rouleaux<\/strong>&nbsp;- Fabriqu\u00e9 \u00e0 partir de plaques d'acier \u00e9paisses pour une meilleure stabilit\u00e9 sous les charges<\/li>\n\n\n\n<li><strong>Rouleaux<\/strong>&nbsp;- Acier tremp\u00e9 avec surfaces de formage rectifi\u00e9es et polies<\/li>\n\n\n\n<li><strong>Paliers<\/strong>&nbsp;- Roulements \u00e0 rouleaux robustes dans des bo\u00eetiers en fonte<\/li>\n\n\n\n<li><strong>Transmission<\/strong>&nbsp;- Engrenages et pignons tremp\u00e9s et rectifi\u00e9s avec cha\u00eenes<\/li>\n\n\n\n<li>** Protections** - Protections en t\u00f4le d'acier pour la s\u00e9curit\u00e9<\/li>\n\n\n\n<li><strong>Contr\u00f4le PLC<\/strong>&nbsp;- Contr\u00f4le tous les moteurs \u00e9lectriques, les capteurs, les op\u00e9rations et les IHM<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">La conception structurelle garantit des vibrations minimales, un formage de pr\u00e9cision et une longue dur\u00e9e de vie.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Normes de conception de l'outillage de roulage<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Les matrices de laminage et l'outillage pour la forme de toit \u00e0 nervures ag classic sont con\u00e7us conform\u00e9ment aux normes internationales :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Forme du profil de la nervure selon les normes AISI, AS\/NZS<\/li>\n\n\n\n<li>Les mat\u00e9riaux des rouleaux sont conformes \u00e0 la norme DIN EN10263 sur les nuances d'acier.<\/li>\n\n\n\n<li>Duret\u00e9 entre 50 et 60 HRC<\/li>\n\n\n\n<li>Rugosit\u00e9 de surface de Ra 0,4\u03bcm \u00e0 0,8\u03bcm<\/li>\n\n\n\n<li>Concentricit\u00e9 du rouleau \u00e0 0,005 mm pr\u00e8s<\/li>\n\n\n\n<li>ISO 2768 grades de tol\u00e9rance pour les dimensions des nervures<\/li>\n\n\n\n<li>Conformit\u00e9 RoHS pour le respect de l'environnement<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">L'outillage de pr\u00e9cision pour les rouleaux est essentiel pour produire efficacement des plaques de toiture nervur\u00e9es de haute qualit\u00e9.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Capacit\u00e9s de production<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">La machine de formage de toits \u00e0 nervures ag classique peut fabriquer des feuilles et des panneaux de toiture pour r\u00e9pondre aux exigences de l'industrie :<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Largeur de la feuille<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Largeur \u00e9troite jusqu'\u00e0 800 mm<\/li>\n\n\n\n<li>Largeur standard jusqu'\u00e0 1250 mm<\/li>\n\n\n\n<li>Grande largeur jusqu'\u00e0 2100 mm<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u00c9paisseur de la feuille<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Calibre l\u00e9ger 0,35 mm \u00e0 0,8 mm<\/li>\n\n\n\n<li>Calibre normal 0,8 mm \u00e0 2,0 mm<\/li>\n\n\n\n<li>Jauge lourde sup\u00e9rieure \u00e0 2,0 mm<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Dimensions des c\u00f4tes<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Hauteur de 15 mm \u00e0 150 mm<\/li>\n\n\n\n<li>Pas\/intervalle de 180 mm \u00e0 350 mm<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Perforation de trous<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Diam\u00e8tre des trous jusqu'\u00e0 20 mm<\/li>\n\n\n\n<li>Espacement des trous jusqu'\u00e0 300 mm<\/li>\n\n\n\n<li>Trous ronds, oblongs, allong\u00e9s<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Fonctionnalit\u00e9s avanc\u00e9es<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Changement rapide des rouleaux<\/li>\n\n\n\n<li>Dispositif d'enroulement des bords<\/li>\n\n\n\n<li>Empileur automatique<\/li>\n\n\n\n<li>Comptage de profils<\/li>\n\n\n\n<li>Tables d'entr\u00e9e et convoyeurs de sortie<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">Fournisseurs et prix<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Parmi les principaux fabricants et fournisseurs de machines de formage de toits \u00e0 nervures ag classiques, on peut citer<\/p>\n\n\n\n<figure class=\"wp-block-table\"><table><thead><tr><th>Fournisseur<\/th><th>Localisation<\/th><th>Fourchette de prix<\/th><\/tr><\/thead><tbody><tr><td>Machines agricoles<\/td><td>Chine<\/td><td>$10000 &#8211; $50000<\/td><\/tr><tr><td>RoofRoll Tech<\/td><td>Inde<\/td><td>$15000 &#8211; $80000<\/td><\/tr><tr><td>Railelectric Corp<\/td><td>L'Europe<\/td><td>$18000 &#8211; $100000<\/td><\/tr><tr><td>Jindezhen Machinery<\/td><td>Chine<\/td><td>$12000 &#8211; $60000<\/td><\/tr><tr><td>Hansoo Engineering<\/td><td>Cor\u00e9e du Sud<\/td><td>$20000 &#8211; $90000<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Niveau d'entr\u00e9e<\/strong>&nbsp;- $15000 \u00e0 $30000<\/li>\n\n\n\n<li><strong>Milieu de gamme<\/strong>&nbsp;- $40000 \u00e0 $60000<\/li>\n\n\n\n<li><strong>Robuste<\/strong>&nbsp;- $80000 \u00e0 $150000<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Les prix varient en fonction de la vitesse, de la largeur, des niveaux d'automatisation et des accessoires en option.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Installation et mise en service<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">L'installation d'une machine \u00e0 former les toits \u00e0 nervures ag classic implique :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Positionnement sur un sol plat et nivel\u00e9<\/li>\n\n\n\n<li>Laisser un espace d'au moins 1000 mm autour pour l'acc\u00e8s<\/li>\n\n\n\n<li>Mise \u00e0 niveau avec une tol\u00e9rance de 0,5 mm \u00e0 l'aide de cales d'\u00e9paisseur<\/li>\n\n\n\n<li>Fixation des boulons de fondation au sol<\/li>\n\n\n\n<li>Alignement des sections de machines et des entra\u00eenements<\/li>\n\n\n\n<li>V\u00e9rification des connexions d'alimentation<\/li>\n\n\n\n<li>Remplissage de lubrifiants dans les engrenages et les roulements<\/li>\n\n\n\n<li>Essais \u00e0 vide et avec des feuilles<\/li>\n\n\n\n<li>R\u00e9glage des param\u00e8tres et des limites de la machine<\/li>\n\n\n\n<li>Test des fonctions de s\u00e9curit\u00e9<\/li>\n\n\n\n<li>D\u00e9bogage et optimisation des op\u00e9rations<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Les vendeurs fournissent des documents d'orientation pour l'installation et des techniciens certifi\u00e9s pour aider \u00e0 l'installation de la profileuse.<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><img decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/swforming.com\/wp-content\/uploads\/2023\/08\/Highway-U-C-Post-Roll-Forming-Machine-01.webp\" alt=\"Machine de profilage de toits \u00e0 nervures classiques ag\" class=\"wp-image-3855\" title=\"\" srcset=\"https:\/\/swforming.com\/wp-content\/uploads\/2023\/08\/Highway-U-C-Post-Roll-Forming-Machine-01.webp 800w, https:\/\/swforming.com\/wp-content\/uploads\/2023\/08\/Highway-U-C-Post-Roll-Forming-Machine-01-400x400.webp 400w, https:\/\/swforming.com\/wp-content\/uploads\/2023\/08\/Highway-U-C-Post-Roll-Forming-Machine-01-100x100.webp 100w, https:\/\/swforming.com\/wp-content\/uploads\/2023\/08\/Highway-U-C-Post-Roll-Forming-Machine-01-600x600.webp 600w, https:\/\/swforming.com\/wp-content\/uploads\/2023\/08\/Highway-U-C-Post-Roll-Forming-Machine-01-300x300.webp 300w, https:\/\/swforming.com\/wp-content\/uploads\/2023\/08\/Highway-U-C-Post-Roll-Forming-Machine-01-150x150.webp 150w, https:\/\/swforming.com\/wp-content\/uploads\/2023\/08\/Highway-U-C-Post-Roll-Forming-Machine-01-768x768.webp 768w, https:\/\/swforming.com\/wp-content\/uploads\/2023\/08\/Highway-U-C-Post-Roll-Forming-Machine-01-12x12.webp 12w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><figcaption><\/figcaption><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Fonctionnement et travail<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">L'utilisation de la machine \u00e0 former les toits \u00e0 nervures ag classic implique :<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Contr\u00f4les pr\u00e9alables<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Disponibilit\u00e9 de l'alimentation \u00e9lectrique<\/li>\n\n\n\n<li>Niveaux de lubrification<\/li>\n\n\n\n<li>Niveau d'huile hydraulique<\/li>\n\n\n\n<li>Contr\u00f4le de l'arr\u00eat d'urgence<\/li>\n\n\n\n<li>\u00c9tat et d\u00e9gagement des rouleaux<\/li>\n\n\n\n<li>Alimentateur pr\u00eat<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>D\u00e9marrage<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Mise sous tension de l'alimentation de contr\u00f4le<\/li>\n\n\n\n<li>D\u00e9marrer les pompes hydrauliques<\/li>\n\n\n\n<li>L'alimentation par \u00e0-coups et le roulage lent pour v\u00e9rifier<\/li>\n\n\n\n<li>R\u00e9gler la vitesse et les param\u00e8tres<\/li>\n\n\n\n<li>Enfiler la feuille dans les rouleaux<\/li>\n\n\n\n<li>Activer le syst\u00e8me de guidage des bords<\/li>\n\n\n\n<li>Augmenter progressivement la vitesse jusqu'\u00e0 la production<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>La course \u00e0 pied<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Contr\u00f4le du courant de roulis et de la pression hydraulique<\/li>\n\n\n\n<li>Contr\u00f4ler en permanence la qualit\u00e9 des feuilles form\u00e9es<\/li>\n\n\n\n<li>Surveillez tout bruit ou vibration anormal<\/li>\n\n\n\n<li>Assurer un flux r\u00e9gulier de feuilles sans bourrage<\/li>\n\n\n\n<li>R\u00e9gler les param\u00e8tres pour contr\u00f4ler les dimensions du profil<\/li>\n\n\n\n<li>Compter les feuilles produites<\/li>\n\n\n\n<li>Empiler correctement les feuilles sur le convoyeur de sortie<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Arr\u00eater<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>R\u00e9duire progressivement la vitesse jusqu'\u00e0 z\u00e9ro<\/li>\n\n\n\n<li>R\u00e9tracter le chargeur jusqu'\u00e0 la derni\u00e8re feuille form\u00e9e<\/li>\n\n\n\n<li>Arr\u00eater les pompes hydrauliques<\/li>\n\n\n\n<li>Couper l'alimentation de la commande<\/li>\n\n\n\n<li>Collecter et empiler correctement les feuilles restantes<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">Entretien et inspection<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Pour maintenir ses performances, la machine de formage de toits \u00e0 nervures ag classique doit faire l'objet d'un entretien r\u00e9gulier :<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Quotidiennement<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Nettoyer les surfaces des machines et enlever les d\u00e9bris de feuilles<\/li>\n\n\n\n<li>V\u00e9rifier les circuits hydrauliques, les lubrifiants et les niveaux d'huile<\/li>\n\n\n\n<li>V\u00e9rifier l'absence de temp\u00e9rature anormale ou de bruit<\/li>\n\n\n\n<li>V\u00e9rifier que toutes les fixations et tous les boulons sont bien serr\u00e9s.<\/li>\n\n\n\n<li>V\u00e9rifier le jeu des bords du rouleau<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Mensuel<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Nettoyer et inspecter tous les roulements et les engrenages<\/li>\n\n\n\n<li>Graisser les roulements et lubrifier les entra\u00eenements<\/li>\n\n\n\n<li>V\u00e9rifier les alignements, les jeux et les tol\u00e9rances<\/li>\n\n\n\n<li>V\u00e9rifier l'usure des guides et des surfaces de roulement<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Trimestrielle<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Test des fonctions d'arr\u00eat d'urgence et de s\u00e9curit\u00e9<\/li>\n\n\n\n<li>V\u00e9rifier les connexions \u00e9lectriques et le panneau<\/li>\n\n\n\n<li>V\u00e9rifier les tuyaux et les cylindres hydrauliques<\/li>\n\n\n\n<li>Remplacement de l'huile hydraulique et du filtre<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Annuel<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Inspection compl\u00e8te des composants<\/li>\n\n\n\n<li>Rincer les syst\u00e8mes de refroidissement et de lubrification<\/li>\n\n\n\n<li>Remplacer les pi\u00e8ces us\u00e9es comme les courroies, les cha\u00eenes<\/li>\n\n\n\n<li>Rev\u00eatement des surfaces des machines pour la protection contre la corrosion<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">La tenue de carnets de bord et de calendriers d'entretien est b\u00e9n\u00e9fique pour un bon entretien.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Comment s\u00e9lectionner la machine \u00e0 former les toits \u00e0 nervures ?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Le choix de la machine de formage de toits \u00e0 nervures ag classique id\u00e9ale d\u00e9pend de la situation :<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>1. Exigences en mati\u00e8re de production<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Dimensions de la t\u00f4le de couverture<\/li>\n\n\n\n<li>Profil et hauteur des c\u00f4tes<\/li>\n\n\n\n<li>\u00c9paisseur et qualit\u00e9 du m\u00e9tal<\/li>\n\n\n\n<li>Vitesse et volume de sortie<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>2. Caract\u00e9ristiques de la machine<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Capacit\u00e9 en largeur de feuille<\/li>\n\n\n\n<li>Gamme d'\u00e9paisseur<\/li>\n\n\n\n<li>Nombre de stations d'ondulation<\/li>\n\n\n\n<li>Vitesse et puissance<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>3. Niveau d'automatisation<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Manuel, semi-automatique ou enti\u00e8rement automatique<\/li>\n\n\n\n<li>Type de syst\u00e8me de contr\u00f4le<\/li>\n\n\n\n<li>Besoins en mati\u00e8re de manutention et d'empilage<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>4. Normes de qualit\u00e9<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Normes de conception de l'outillage de laminage<\/li>\n\n\n\n<li>Pr\u00e9cision et r\u00e9p\u00e9tabilit\u00e9<\/li>\n\n\n\n<li>Caract\u00e9ristiques de contr\u00f4le des vibrations<\/li>\n\n\n\n<li>M\u00e9thode de guidage des feuilles<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>5. R\u00e9f\u00e9rences du fournisseur<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Exp\u00e9rience et installations ant\u00e9rieures<\/li>\n\n\n\n<li>Pr\u00e9sence locale pour le soutien<\/li>\n\n\n\n<li>Respect des normes de s\u00e9curit\u00e9<\/li>\n\n\n\n<li>Expertise en mati\u00e8re de conception d'outils de laminage<\/li>\n\n\n\n<li>Services de formation propos\u00e9s<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Le choix du bon mod\u00e8le de machine de formage de toits \u00e0 nervures classiques ag garantit que les exigences de production de toitures sont satisfaites de mani\u00e8re fiable et efficace.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Comparaison entre les mod\u00e8les de machines<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Voici une comparaison entre deux mod\u00e8les de machines \u00e0 former les toits \u00e0 nervures classiques :<\/p>\n\n\n\n<figure class=\"wp-block-table\"><table><thead><tr><th>Param\u00e8tres<\/th><th>Mod\u00e8le RRF-16<\/th><th>Mod\u00e8le RRF-20<\/th><\/tr><\/thead><tbody><tr><td>Largeur de la feuille<\/td><td>1000mm<\/td><td>1500mm<\/td><\/tr><tr><td>\u00c9paisseur de la feuille<\/td><td>0,5-1,6 mm<\/td><td>0,4-2,0 mm<\/td><\/tr><tr><td>Hauteur des c\u00f4tes<\/td><td>25-120mm<\/td><td>20-150mm<\/td><\/tr><tr><td>Vitesse<\/td><td>10m\/min<\/td><td>15m\/min<\/td><\/tr><tr><td>Puissance<\/td><td>7,5 kW<\/td><td>11kW<\/td><\/tr><tr><td>Stands<\/td><td>16<\/td><td>20<\/td><\/tr><tr><td>Contr\u00f4le<\/td><td>Semi-auto<\/td><td>Automate programmable enti\u00e8rement automatique<\/td><\/tr><tr><td>Changement de r\u00f4le<\/td><td>Manuel<\/td><td>Aliment\u00e9<\/td><\/tr><tr><td>Prix<\/td><td>$45000<\/td><td>$95000<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">La RRF-20 est plus large, plus automatis\u00e9e, plus rapide et peut traiter des feuilles plus lourdes que la RRF-16. Mais la RRF-16 convient aux besoins des petites et moyennes productions et est moins co\u00fbteuse.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Avantages et inconv\u00e9nients<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Avantages<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Efficacit\u00e9 et rendement \u00e9lev\u00e9s de la production<\/li>\n\n\n\n<li>Flexible pour produire diff\u00e9rents profils de nervures<\/li>\n\n\n\n<li>Construction durable et robuste<\/li>\n\n\n\n<li>Protections de s\u00e9curit\u00e9 avanc\u00e9es<\/li>\n\n\n\n<li>Co\u00fbts d'exploitation inf\u00e9rieurs \u00e0 ceux des autres m\u00e9thodes<\/li>\n\n\n\n<li>Qualit\u00e9 constante et tol\u00e9rances \u00e9troites<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Limites<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Co\u00fbt d'investissement initial \u00e9lev\u00e9<\/li>\n\n\n\n<li>Entretien r\u00e9gulier n\u00e9cessaire<\/li>\n\n\n\n<li>Le changement de rouleau n\u00e9cessite des temps d'arr\u00eat<\/li>\n\n\n\n<li>R\u00e9sistance et ductilit\u00e9 limit\u00e9es de la t\u00f4le<\/li>\n\n\n\n<li>N\u00e9cessit\u00e9 d'une main-d'\u0153uvre qualifi\u00e9e pour l'exploitation et la maintenance<\/li>\n\n\n\n<li>La configuration corrig\u00e9e limite les changements de profil<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><img decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/swforming.com\/wp-content\/uploads\/2023\/07\/Stand-Seaming-Roof-Panel-Roll-Forming-Machine-2.webp\" alt=\"Machine de profilage de toits \u00e0 nervures classiques ag\" class=\"wp-image-3496\" title=\"\" srcset=\"https:\/\/swforming.com\/wp-content\/uploads\/2023\/07\/Stand-Seaming-Roof-Panel-Roll-Forming-Machine-2.webp 800w, https:\/\/swforming.com\/wp-content\/uploads\/2023\/07\/Stand-Seaming-Roof-Panel-Roll-Forming-Machine-2-400x400.webp 400w, https:\/\/swforming.com\/wp-content\/uploads\/2023\/07\/Stand-Seaming-Roof-Panel-Roll-Forming-Machine-2-100x100.webp 100w, https:\/\/swforming.com\/wp-content\/uploads\/2023\/07\/Stand-Seaming-Roof-Panel-Roll-Forming-Machine-2-600x600.webp 600w, https:\/\/swforming.com\/wp-content\/uploads\/2023\/07\/Stand-Seaming-Roof-Panel-Roll-Forming-Machine-2-300x300.webp 300w, https:\/\/swforming.com\/wp-content\/uploads\/2023\/07\/Stand-Seaming-Roof-Panel-Roll-Forming-Machine-2-150x150.webp 150w, https:\/\/swforming.com\/wp-content\/uploads\/2023\/07\/Stand-Seaming-Roof-Panel-Roll-Forming-Machine-2-768x768.webp 768w, https:\/\/swforming.com\/wp-content\/uploads\/2023\/07\/Stand-Seaming-Roof-Panel-Roll-Forming-Machine-2-12x12.webp 12w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><figcaption><\/figcaption><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">FAQ<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Q : Quelles t\u00f4les peuvent \u00eatre form\u00e9es sur ces machines ?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A : G\u00e9n\u00e9ralement acier doux, acier galvanis\u00e9, aluminium, acier inoxydable dans les limites de ductilit\u00e9.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Q : Quels sont les profils de nervures qui peuvent \u00eatre produits ?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A : Profils trap\u00e9zo\u00efdaux, sinuso\u00efdaux, courbes, angulaires de diff\u00e9rentes hauteurs et espacements.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Q : Quels sont les principaux aspects de la maintenance ?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A : Lubrifier les rouleaux et les entra\u00eenements, inspecter l'usure de l'outillage, v\u00e9rifier les alignements et les d\u00e9gagements, tester les syst\u00e8mes de s\u00e9curit\u00e9.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Q : Quelles sont les m\u00e9thodes de guidage des feuilles utilis\u00e9es ?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A : Guides lat\u00e9raux \u00e0 rouleaux, guides int\u00e9rieurs extensibles, rouleaux de pressage des bords, rouleaux de direction.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Q : Quels sont les niveaux d'automatisation disponibles ?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">R : Manipulation manuelle, semi-automatique avec fonctions \u00e9lectriques et enti\u00e8rement automatis\u00e9e avec empilage.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Q : Quelle est la rapidit\u00e9 du processus de changement de rouleau ?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">R : 10 \u00e0 20 minutes pour un changement manuel. Moins de 5 minutes pour le changement automatique des rouleaux motoris\u00e9s.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Q : Quelles op\u00e9rations secondaires peuvent \u00eatre int\u00e9gr\u00e9es ?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">R : D\u00e9coupage, perforation, encochage, coupe de longueur, ourlet de bord et moulage.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Q : Quels sont les facteurs qui influencent le prix ?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">R : Largeur, vitesse, niveau d'automatisation, caract\u00e9ristiques de puissance, accessoires ajout\u00e9s comme l'empileur automatique.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Conclusion<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">La profileuse de toiture \u00e0 nervures ag classic permet de produire efficacement sur site des plaques de toiture nervur\u00e9es de qualit\u00e9. Avec une gamme de mod\u00e8les, de largeurs, de niveaux d'automatisation, de vitesses et de capacit\u00e9s, ces profileuses r\u00e9pondent aux besoins des petits ateliers comme des grands fabricants de toitures industrielles. En s\u00e9lectionnant les sp\u00e9cifications appropri\u00e9es de la machine en fonction des profils de toiture, des propri\u00e9t\u00e9s du m\u00e9tal, des besoins de qualit\u00e9 et des volumes de production, les fabricants peuvent b\u00e9n\u00e9ficier d'une installation rapide, de co\u00fbts d'exploitation r\u00e9duits et d'une fabrication flexible. Gr\u00e2ce \u00e0 un entretien r\u00e9gulier et \u00e0 une utilisation comp\u00e9tente, les profileuses de toiture \u00e0 nervures ag classic fonctionnent de mani\u00e8re fiable pendant des ann\u00e9es de production de toitures.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/en.wikipedia.org\/wiki\/Roll_forming\" target=\"_blank\" rel=\"noreferrer noopener\">en savoir plus Formage de rouleaux<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>The ag classic rib roof roll forming machine is an essential equipment for manufacturing ribbed metal roofing panels and decking sheets efficiently. This guide provides a comprehensive overview of ag classic rib roof roll forming machines, their working, types, applications, specifications, suppliers, installation, operation, maintenance, and selection criteria. Overview of Ag Classic Rib Roof Roll [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":3855,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[1],"tags":[],"class_list":["post-4190","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":7}},"acf":[],"_links":{"self":[{"href":"https:\/\/swforming.com\/fr\/wp-json\/wp\/v2\/posts\/4190","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/swforming.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/swforming.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/swforming.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/swforming.com\/fr\/wp-json\/wp\/v2\/comments?post=4190"}],"version-history":[{"count":1,"href":"https:\/\/swforming.com\/fr\/wp-json\/wp\/v2\/posts\/4190\/revisions"}],"predecessor-version":[{"id":4191,"href":"https:\/\/swforming.com\/fr\/wp-json\/wp\/v2\/posts\/4190\/revisions\/4191"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/swforming.com\/fr\/wp-json\/wp\/v2\/media\/3855"}],"wp:attachment":[{"href":"https:\/\/swforming.com\/fr\/wp-json\/wp\/v2\/media?parent=4190"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/swforming.com\/fr\/wp-json\/wp\/v2\/categories?post=4190"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/swforming.com\/fr\/wp-json\/wp\/v2\/tags?post=4190"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}