{"id":4162,"date":"2023-10-19T06:02:50","date_gmt":"2023-10-19T06:02:50","guid":{"rendered":"https:\/\/swforming.com\/?p=4162"},"modified":"2023-10-19T06:03:20","modified_gmt":"2023-10-19T06:03:20","slug":"stud-and-track-roll-forming-machines","status":"publish","type":"post","link":"https:\/\/swforming.com\/es\/stud-and-track-roll-forming-machines\/","title":{"rendered":"Perfiladoras de esp\u00e1rragos y carriles"},"content":{"rendered":"<p class=\"wp-block-paragraph\">El perfilado es un proceso de trabajo del metal en el que la chapa se dobla gradualmente en un perfil de secci\u00f3n transversal deseada a trav\u00e9s de una serie de estaciones de rodillos. <a href=\"https:\/\/swforming.com\/es\/producto\/\">Perfiladoras de esp\u00e1rragos y carriles <\/a>se utilizan para formar montantes y carriles de acero enrollado que se emplean en sistemas de entramado de muros y muros cortina en la industria de la construcci\u00f3n.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Visi\u00f3n general de las perfiladoras de esp\u00e1rragos y carriles<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Las perfiladoras de esp\u00e1rragos y ra\u00edles transforman tiras planas de chapa met\u00e1lica en esp\u00e1rragos y ra\u00edles con dimensiones de secci\u00f3n transversal espec\u00edficas haci\u00e9ndolos pasar por una serie de pasos con rodillos contorneados. Este proceso continuo y automatizado forma los flejes en canales en forma de \"C\" o \"U\" mediante el perfilado en fr\u00edo sin utilizar calor.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Estos son los detalles clave sobre las perfiladoras de esp\u00e1rragos y carriles:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Funci\u00f3n:<\/strong>&nbsp;Fabricar esp\u00e1rragos y ra\u00edles a partir de bobinas de acero de diferentes tama\u00f1os seg\u00fan el perfil y la secci\u00f3n transversal especificados.<\/li>\n\n\n\n<li><strong>Trabajando:<\/strong>&nbsp;Conformado en fr\u00edo de chapas met\u00e1licas mediante curvado progresivo a lo largo de una trayectoria lineal a trav\u00e9s de una serie de rodillos.<\/li>\n\n\n\n<li><strong>Proceso:<\/strong>&nbsp;La chapa de acero enrollada se hace pasar por una serie de estaciones de rodillos para darle gradualmente la forma deseada. El n\u00famero y el contorno de los rodillos determinan la forma final.<\/li>\n\n\n\n<li><strong>Componentes clave:<\/strong>&nbsp;Desenrollador, rodillos de alimentaci\u00f3n, rodillos de desglose, rodillos de acabado, rodillos de reforma, estaci\u00f3n de agujeros preperforados, cizalla y corte, apilador<\/li>\n\n\n\n<li><strong>Conduce:<\/strong>&nbsp;Servomotores el\u00e9ctricos para cada estaci\u00f3n de rodillos<\/li>\n\n\n\n<li><strong>Automatizaci\u00f3n:<\/strong>&nbsp;Totalmente autom\u00e1tica con controles de velocidad, avance y corte<\/li>\n\n\n\n<li><strong>Materiales:<\/strong>&nbsp;Bobinas de acero galvanizado, acero inoxidable o aluminio de 0,5 mm a 3 mm de espesor<\/li>\n\n\n\n<li><strong>Productividad:<\/strong>&nbsp;Velocidades de conformado de hasta 100 m\/min en funci\u00f3n del espesor<\/li>\n\n\n\n<li><strong>Perfiles:<\/strong>&nbsp;Pernos en forma de \"C\", rieles en forma de \"U\", perfiles en \"L\", en \"Z\" o personalizados<\/li>\n\n\n\n<li><strong>Tallas:<\/strong>&nbsp;Espesor de 0,5 mm a 3 mm, anchura de hasta 300 mm, altura de banda de hasta 300 mm<\/li>\n\n\n\n<li><strong>Aplicaciones:<\/strong>&nbsp;Muros, muros cortina, cerchas, estructuras de acero para edificios<\/li>\n\n\n\n<li><strong>Ventajas:<\/strong>&nbsp;Alta velocidad, calidad superior, consistencia, reducci\u00f3n de residuos, bajo coste operativo<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">Tipos de m\u00e1quinas perfiladoras de esp\u00e1rragos y rieles<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Existen dos tipos principales de perfiladoras de esp\u00e1rragos y v\u00edas:<\/p>\n\n\n\n<figure class=\"wp-block-table\"><table><thead><tr><th><strong>Tipo<\/strong><\/th><th><strong>Descripci\u00f3n<\/strong><\/th><\/tr><\/thead><tbody><tr><td>L\u00edneas combinadas de esp\u00e1rrago y ra\u00edl<\/td><td>M\u00e1quinas con flexibilidad para producir tanto tacos como orugas en la misma l\u00ednea seg\u00fan la aplicaci\u00f3n cambiando r\u00e1pidamente los rodillos.<\/td><\/tr><tr><td>L\u00edneas de esp\u00e1rragos o v\u00edas dedicadas<\/td><td>M\u00e1quinas dise\u00f1adas para producir un solo perfil, es decir, ya sea tacos u orugas con una configuraci\u00f3n fija de rodillos.<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Diferencias clave:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Las l\u00edneas combinadas ofrecen flexibilidad pero una productividad inferior, de unos 60-70 m\/min.<\/li>\n\n\n\n<li>Las l\u00edneas dedicadas tienen un mayor rendimiento, de hasta 100 m\/min, pero s\u00f3lo pueden fabricar un perfil<\/li>\n\n\n\n<li>Las l\u00edneas combinadas necesitan un cambio r\u00e1pido de utillaje; las l\u00edneas dedicadas tienen utillaje fijo<\/li>\n\n\n\n<li>Las l\u00edneas combinadas ocupan m\u00e1s espacio; las dedicadas son compactas y menos costosas<\/li>\n\n\n\n<li>Elija l\u00edneas dedicadas para la producci\u00f3n en serie; l\u00edneas combinadas para vol\u00famenes m\u00e1s peque\u00f1os<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">Componentes principales de las m\u00e1quinas perfiladoras de esp\u00e1rragos y carriles<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Las perfiladoras de esp\u00e1rragos y carriles constan de una serie de estaciones o soportes de rodillos para dar forma al material, junto con mecanismos de desenrollado, alimentaci\u00f3n, corte y apilado.<\/p>\n\n\n\n<figure class=\"wp-block-table\"><table><thead><tr><th><strong>Componente<\/strong><\/th><th><strong>Funci\u00f3n<\/strong><\/th><\/tr><\/thead><tbody><tr><td>desenrollador<\/td><td>Sujeta la bobina de chapa y la introduce en la l\u00ednea de perfilado<\/td><\/tr><tr><td>Mecanismo de alimentaci\u00f3n<\/td><td>Controla la velocidad de alimentaci\u00f3n y la fuerza de la banda en los rodillos<\/td><\/tr><tr><td>Estaci\u00f3n de rodillos de aver\u00eda<\/td><td>Forma el perfil inicial en forma de U o C con rodillos horizontales superiores e inferiores.<\/td><\/tr><tr><td>Estaciones de rodillos de acabado<\/td><td>Perfeccionamiento del perfil a las dimensiones exactas con rodillos contorneados<\/td><\/tr><tr><td>Unidad de prepunzonado<\/td><td>Perfora agujeros en el alma del perfil seg\u00fan el dise\u00f1o<\/td><\/tr><tr><td>Cizallado y corte<\/td><td>Corta los travesa\u00f1os y rieles de formaci\u00f3n continua a las longitudes requeridas.<\/td><\/tr><tr><td>Apilado<\/td><td>Recoge las piezas cortadas acabadas<\/td><\/tr><tr><td>Armario el\u00e9ctrico<\/td><td>Alberga el cuadro el\u00e9ctrico, los controles PLC y la HMI<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"746\" height=\"1024\" src=\"https:\/\/swforming.com\/wp-content\/uploads\/2023\/09\/Hc309666d13e54f459f65259dc37eed0as-746x1024.jpg\" alt=\"m\u00e1quina perfiladora de esp\u00e1rragos y rieles\" class=\"wp-image-4081\" title=\"\" srcset=\"\" sizes=\"(max-width: 746px) 100vw, 746px\" data-srcset=\"\" \/><figcaption><\/figcaption><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">Especificaciones t\u00edpicas y normas de dise\u00f1o<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Las perfiladoras de esp\u00e1rragos y carriles se dise\u00f1an seg\u00fan los requisitos y normas de la aplicaci\u00f3n. A continuaci\u00f3n se muestran las especificaciones t\u00edpicas:<\/p>\n\n\n\n<figure class=\"wp-block-table\"><table><thead><tr><th><strong>Par\u00e1metros<\/strong><\/th><th><strong>Valores t\u00edpicos<\/strong><\/th><\/tr><\/thead><tbody><tr><td>Velocidad de formaci\u00f3n<\/td><td>Hasta 100 m\/min<\/td><\/tr><tr><td>Material Grosor<\/td><td>0,5 mm a 3 mm<\/td><\/tr><tr><td>Ancho de banda<\/td><td>De 50 mm a 300 mm<\/td><\/tr><tr><td>Estaciones de rodillos<\/td><td>10 a 16 a\u00f1os<\/td><\/tr><tr><td>Material del rodillo<\/td><td>Acero aleado o aleaci\u00f3n de titanio<\/td><\/tr><tr><td>Di\u00e1metro del rollo<\/td><td>100 a 300 mm<\/td><\/tr><tr><td>Altura del rollo<\/td><td>50 a 100 mm<\/td><\/tr><tr><td>Potencia necesaria<\/td><td>15 a 30 kW<\/td><\/tr><tr><td>Peso de la m\u00e1quina<\/td><td>8000 a 15000 kg<\/td><\/tr><tr><td>Tama\u00f1o de la m\u00e1quina<\/td><td>15m x 3m x 3m (LxAxA)<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Los perfiles, dimensiones y tama\u00f1os de los esp\u00e1rragos y ra\u00edles se ajustan a normas como AISI S200, AS\/NZS 4600, EN 14195. Los patrones de los orificios siguen normas como los patrones de los tornillos TEK.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Aplicaciones y usos de esp\u00e1rragos y ra\u00edles<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Las principales aplicaciones de los esp\u00e1rragos y las orugas son:<\/p>\n\n\n\n<figure class=\"wp-block-table\"><table><thead><tr><th><strong>Solicitud<\/strong><\/th><th><strong>Detalles de uso<\/strong><\/th><\/tr><\/thead><tbody><tr><td>Marcos de pared<\/td><td>Utilizados como muros de carga y sin carga interiores y exteriores<\/td><\/tr><tr><td>Muros cortina<\/td><td>Montantes y travesa\u00f1os para fachadas de acristalamiento estructural<\/td><\/tr><tr><td>Armaz\u00f3n del techo<\/td><td>Tes principales y transversales para falsos techos<\/td><\/tr><tr><td>Cerchas<\/td><td>Cordones superiores e inferiores, almas de cerchas met\u00e1licas<\/td><\/tr><tr><td>Entresuelos<\/td><td>Viguetas para suelos t\u00e9cnicos en edificios<\/td><\/tr><tr><td>Barreras ac\u00fasticas<\/td><td>Postes verticales y canales para muros antirruido<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Otras aplicaciones incluyen entreplantas, sistemas de estanter\u00edas, mamparas de seguridad, edificios agr\u00edcolas, estructuras prefabricadas, etc.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los montantes y travesa\u00f1os funcionan como componentes de entramado que forman el esqueleto estructural actuando como montantes verticales, travesa\u00f1os horizontales, arriostramientos y canales de enrasado. Se ensamblan in situ mediante tornillos, pernos o soldadura.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Comparaci\u00f3n de fabricantes de perfiladoras de esp\u00e1rragos y carriles<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Hay muchos fabricantes l\u00edderes en todo el mundo que producen perfiladoras de esp\u00e1rragos y de carriles. He aqu\u00ed una comparaci\u00f3n entre los principales fabricantes:<\/p>\n\n\n\n<figure class=\"wp-block-table\"><table><thead><tr><th><strong>Compa\u00f1\u00eda<\/strong><\/th><th><strong>Ubicaci\u00f3n<\/strong><\/th><th><strong>Tasa de producci\u00f3n<\/strong><\/th><th><strong>Tipo rodillo<\/strong><\/th><th><strong>Controla<\/strong><\/th><th><strong>Tama\u00f1o de la bobina<\/strong><\/th><\/tr><\/thead><tbody><tr><td>M\u00e1quinas ACL<\/td><td>Italia<\/td><td>80 m\/min<\/td><td>Pir\u00e1mide<\/td><td>PLC+HMI<\/td><td>M\u00e1x. 1500 kg<\/td><\/tr><tr><td>Metform<\/td><td>Turqu\u00eda<\/td><td>100 m\/min<\/td><td>Alto par<\/td><td>PLC+HMI<\/td><td>M\u00e1x. 2000 kg<\/td><\/tr><tr><td>Formtek<\/td><td>EE.UU.<\/td><td>90 m\/min<\/td><td>Aleaci\u00f3n de titanio<\/td><td>CNC<\/td><td>M\u00e1x. 2500 kg<\/td><\/tr><tr><td>Everest<\/td><td>China<\/td><td>70 m\/min<\/td><td>Acero aleado<\/td><td>PLC<\/td><td>M\u00e1x. 1000 kg<\/td><\/tr><tr><td>Shandong.<\/td><td>China<\/td><td>60 m\/min<\/td><td>Acero aleado<\/td><td>PLC<\/td><td>M\u00e1x. 1500 kg<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Diferencias clave:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Empresas europeas como ACL y Metform proporcionan mayores velocidades, par y producci\u00f3n<\/li>\n\n\n\n<li>Los fabricantes estadounidenses y europeos ofrecen controles y automatismos m\u00e1s avanzados<\/li>\n\n\n\n<li>Las empresas chinas ofrecen soluciones rentables con menores velocidades y capacidades<\/li>\n\n\n\n<li>Las mejores marcas, como ACL y Metform, cobran un sobreprecio por su calidad y rendimiento.<\/li>\n\n\n\n<li>Elija en funci\u00f3n de la cadencia de producci\u00f3n, el tama\u00f1o de la bobina, la complejidad del perfil y los presupuestos<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">Detalles de los precios de las perfiladoras de esp\u00e1rragos y carriles<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">El precio de las perfiladoras de esp\u00e1rragos y carriles depende de la velocidad de producci\u00f3n, la configuraci\u00f3n de la l\u00ednea, las caracter\u00edsticas de automatizaci\u00f3n, la marca y la ubicaci\u00f3n. He aqu\u00ed un resumen:<\/p>\n\n\n\n<figure class=\"wp-block-table\"><table><thead><tr><th><strong>Velocidad (m\/min)<\/strong><\/th><th><strong>Tipo<\/strong><\/th><th><strong>Automatizaci\u00f3n<\/strong><\/th><th><strong>Precios<\/strong><\/th><\/tr><\/thead><tbody><tr><td>Hasta el 40<\/td><td>Mec\u00e1nico\/Semiautom\u00e1tico<\/td><td>B\u00e1sico<\/td><td>USD 150.000 - 250.000<\/td><\/tr><tr><td>40 \u2013 70<\/td><td>Semiautom\u00e1tico<\/td><td>Medio<\/td><td>USD 200.000 - 350.000<\/td><\/tr><tr><td>70 \u2013 100<\/td><td>Totalmente autom\u00e1tico<\/td><td>Avanzado<\/td><td>300.000 - 500.000 USD<\/td><\/tr><tr><td>100+<\/td><td>Alta velocidad<\/td><td>Sofisticado<\/td><td>M\u00c1S DE 400.000 D\u00d3LARES<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Controladores de precios:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Velocidad de producci\u00f3n y requisitos de producci\u00f3n<\/li>\n\n\n\n<li>Nivel de automatizaci\u00f3n: manual, semiautom\u00e1tico o totalmente autom\u00e1tico<\/li>\n\n\n\n<li>Complejidad del material y el perfil del rodillo<\/li>\n\n\n\n<li>Funciones adicionales como la perforaci\u00f3n de agujeros<\/li>\n\n\n\n<li>Las marcas europeas\/americanas de renombre tienen precios m\u00e1s altos<\/li>\n\n\n\n<li>Comprar l\u00edneas completas cuesta m\u00e1s que comprar componentes<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">C\u00f3mo seleccionar su proveedor de perfiladoras de esp\u00e1rragos y carriles<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Elegir el proveedor adecuado de perfiladoras de esp\u00e1rragos y carriles es crucial para obtener un equipo que satisfaga las necesidades, con un buen servicio postventa. He aqu\u00ed algunos consejos para la selecci\u00f3n:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Factores a tener en cuenta<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Conocimientos t\u00e9cnicos y experiencia del proveedor<\/li>\n\n\n\n<li>Velocidades de producci\u00f3n y cadencias requeridas<\/li>\n\n\n\n<li>Calidad del mecanizado, los componentes y el acabado<\/li>\n\n\n\n<li>Opciones de automatizaci\u00f3n y control<\/li>\n\n\n\n<li>Dise\u00f1o de rodillos para la forma de perfil necesaria<\/li>\n\n\n\n<li>Tama\u00f1o y grosor de la bobina a manipular<\/li>\n\n\n\n<li>Cambio r\u00e1pido entre perfiles en caso necesario<\/li>\n\n\n\n<li>Asistencia y formaci\u00f3n para la instalaci\u00f3n<\/li>\n\n\n\n<li>Programas de mantenimiento y calidad del servicio<\/li>\n\n\n\n<li>Disponibilidad de piezas de recambio y log\u00edstica de suministro<\/li>\n\n\n\n<li>Gastos generales de compra y funcionamiento<\/li>\n\n\n\n<li>Rese\u00f1as y reputaci\u00f3n mediante referencias de clientes<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Pasos de la evaluaci\u00f3n<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Definir el volumen de producci\u00f3n y los requisitos de perfil<\/li>\n\n\n\n<li>Buscar opciones en directorios en l\u00ednea y ferias comerciales<\/li>\n\n\n\n<li>Preseleccionar a los proveedores en funci\u00f3n de sus capacidades y opiniones<\/li>\n\n\n\n<li>Comprobaci\u00f3n de certificaciones, visita in situ si es posible<\/li>\n\n\n\n<li>Revisar presupuestos detallados de varios proveedores<\/li>\n\n\n\n<li>Evaluar el servicio posventa y la asistencia a largo plazo<\/li>\n\n\n\n<li>Negociar precios y condiciones de pago<\/li>\n\n\n\n<li>Seleccionar al proveedor que ofrezca la mejor relaci\u00f3n calidad-precio global<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">La elecci\u00f3n del socio adecuado influye enormemente en el rendimiento de la m\u00e1quina, su vida \u00fatil y el coste total de propiedad. Invierta tiempo en hacer la mejor elecci\u00f3n.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Instalaci\u00f3n y funcionamiento de las perfiladoras de esp\u00e1rragos y carriles<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Los procedimientos adecuados de instalaci\u00f3n y funcionamiento son vitales para optimizar el rendimiento de la perfiladora de esp\u00e1rragos y carriles. Estas son las directrices:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Instalaci\u00f3n<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Preparaci\u00f3n de cimientos nivelados y sin vibraciones seg\u00fan la carga del suelo<\/li>\n\n\n\n<li>Posicionar la m\u00e1quina seg\u00fan los planos de disposici\u00f3n, anclar firmemente<\/li>\n\n\n\n<li>Instalar las mesas de entrada y salida a la altura y \u00e1ngulo correctos.<\/li>\n\n\n\n<li>Conectar l\u00edneas el\u00e9ctricas, neum\u00e1ticas e hidr\u00e1ulicas<\/li>\n\n\n\n<li>Instale protecciones de seguridad para los puntos de pellizco y las piezas m\u00f3viles<\/li>\n\n\n\n<li>Integrar la tronzadora si est\u00e1 separada de la m\u00e1quina principal<\/li>\n\n\n\n<li>Pruebe la m\u00e1quina vac\u00eda y compruebe su funcionamiento<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Operaci\u00f3n<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Siga el manual de instrucciones del fabricante para la secuencia de puesta en marcha<\/li>\n\n\n\n<li>Carga de bobina de material y propiedades especificados en desenrollador<\/li>\n\n\n\n<li>Ajustar velocidad, avance, corte y otros par\u00e1metros<\/li>\n\n\n\n<li>Ajustar indicadores y sensores, programar el control seg\u00fan sea necesario<\/li>\n\n\n\n<li>Hacer funcionar la m\u00e1quina sin existencias para comprobar que los rodillos giran correctamente<\/li>\n\n\n\n<li>Alimentaci\u00f3n de material de prueba a trav\u00e9s de toda la m\u00e1quina y depuraci\u00f3n<\/li>\n\n\n\n<li>Iniciar la producci\u00f3n cuando la m\u00e1quina fabrique los componentes correctamente<\/li>\n\n\n\n<li>Supervise la l\u00ednea durante el funcionamiento, ajuste la configuraci\u00f3n si es necesario<\/li>\n\n\n\n<li>Realizar el mantenimiento peri\u00f3dico durante las pausas<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Seguridad<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Llevar equipo de protecci\u00f3n, como casco y calzado de seguridad, al trabajar<\/li>\n\n\n\n<li>Mantenga las manos alejadas del alojamiento del rodillo y de las zonas de flujo de material<\/li>\n\n\n\n<li>Detenga el funcionamiento si se producen vibraciones, ruidos u otros problemas inesperados.<\/li>\n\n\n\n<li>Siga los procedimientos de bloqueo y etiquetado durante las tareas de mantenimiento o reparaci\u00f3n.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Una instalaci\u00f3n adecuada combinada con pr\u00e1cticas de funcionamiento disciplinadas dar\u00e1 como resultado a\u00f1os de rendimiento \u00f3ptimo. Se recomienda encarecidamente la formaci\u00f3n por parte de los t\u00e9cnicos del proveedor.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Mantenimiento de perfiladoras de esp\u00e1rragos y carriles<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">El mantenimiento preventivo regular es esencial para un funcionamiento sin problemas y la m\u00e1xima productividad de la l\u00ednea. A continuaci\u00f3n se indican las pautas de mantenimiento:<\/p>\n\n\n\n<figure class=\"wp-block-table\"><table><thead><tr><th><strong>Actividad<\/strong><\/th><th><strong>Frecuencia<\/strong><\/th><th><strong>Detalles<\/strong><\/th><\/tr><\/thead><tbody><tr><td>Inspecci\u00f3n de rodillos<\/td><td>Diario<\/td><td>Comprobaci\u00f3n de da\u00f1os y desgaste<\/td><\/tr><tr><td>Comprobaci\u00f3n del cierre<\/td><td>Diario<\/td><td>Garantizar la estanqueidad<\/td><\/tr><tr><td>Lubricaci\u00f3n<\/td><td>Semanal<\/td><td>Engrasar rodamientos y cadenas<\/td><\/tr><tr><td>Sistema hidr\u00e1ulico<\/td><td>Mensualmente<\/td><td>Comprobar el l\u00edquido, rellenar si es necesario<\/td><\/tr><tr><td>Sistema neum\u00e1tico<\/td><td>Mensualmente<\/td><td>Drenar la humedad, comprobar si hay fugas<\/td><\/tr><tr><td>Electricidad<\/td><td>Mensualmente<\/td><td>Comprobar conexiones, cables<\/td><\/tr><tr><td>Cambio de rodillo<\/td><td>Anualmente<\/td><td>Sustituir seg\u00fan desgaste y volver a enrollar<\/td><\/tr><tr><td>Aceite de la caja de cambios<\/td><td>Anualmente<\/td><td>Cambiar el aceite<\/td><\/tr><tr><td>Gu\u00edas lineales<\/td><td>Anualmente<\/td><td>Inspeccionar y lubricar<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Consejos para el mantenimiento<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Llevar un diario de mantenimiento<\/li>\n\n\n\n<li>Sustituya los rodillos desgastados para mantener la calidad del perfil<\/li>\n\n\n\n<li>Mantener un inventario de repuesto de piezas de desgaste como cadenas, cojinetes<\/li>\n\n\n\n<li>Formar al equipo interno u obtener un contrato de servicio anual<\/li>\n\n\n\n<li>Programar revisiones generales cada 3-5 a\u00f1os seg\u00fan sea necesario.<\/li>\n\n\n\n<li>Siga el manual de mantenimiento del fabricante<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Con un mantenimiento y unas revisiones programadas, las m\u00e1quinas pueden ofrecer m\u00e1s de 20 a\u00f1os de producci\u00f3n fiable. Esto reduce el coste total de propiedad a lo largo de la vida \u00fatil del equipo.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Ventajas y beneficios del perfilado de esp\u00e1rragos y carriles<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Las perfiladoras de esp\u00e1rragos y carriles ofrecen varias ventajas que las hacen ventajosas para los fabricantes:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Beneficios<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Altas velocidades de producci\u00f3n de hasta 100 m\/min<\/li>\n\n\n\n<li>Cambios r\u00e1pidos entre tama\u00f1os y perfiles<\/li>\n\n\n\n<li>Dimensiones de perfil coherentes y uniformes<\/li>\n\n\n\n<li>Reducci\u00f3n del desperdicio de material gracias a la precisi\u00f3n del conformado<\/li>\n\n\n\n<li>Bajos costes de explotaci\u00f3n en comparaci\u00f3n con otros procesos<\/li>\n\n\n\n<li>Necesidad m\u00ednima de procesos de acabado secundarios<\/li>\n\n\n\n<li>Alto tiempo de actividad y productividad gracias a la automatizaci\u00f3n<\/li>\n\n\n\n<li>Capacidad para formar formas complejas y personalizadas<\/li>\n\n\n\n<li>Producci\u00f3n justo a tiempo con un peque\u00f1o inventario de bobinas<\/li>\n\n\n\n<li>Trabajo m\u00e1s seguro en comparaci\u00f3n con la fabricaci\u00f3n manual de esp\u00e1rragos<\/li>\n\n\n\n<li>Bajos niveles de ruido en comparaci\u00f3n con otros procesos de trabajo del metal<\/li>\n\n\n\n<li>Proporciona componentes acabados listos para su instalaci\u00f3n<\/li>\n\n\n\n<li>Produce componentes de construcci\u00f3n ligeros pero de gran resistencia<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">El funcionamiento automatizado y continuo permite a las l\u00edneas de perfilado producir grandes vol\u00famenes con menos mano de obra de forma rentable. Esto la hace ideal para aplicaciones de producci\u00f3n en masa.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Limitaciones y retos del perfilado de pernos y carriles<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Aunque ofrece muchas ventajas, el perfilado de esp\u00e1rragos y v\u00edas tambi\u00e9n plantea algunas limitaciones y retos, como se indica a continuaci\u00f3n:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Limitaciones<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>No es econ\u00f3mico para vol\u00famenes de producci\u00f3n bajos<\/li>\n\n\n\n<li>Se requiere una importante inversi\u00f3n de capital inicial<\/li>\n\n\n\n<li>Los cambios de perfil complejos requieren cambios de utillaje<\/li>\n\n\n\n<li>Limitado al uso de bobinas, no puede utilizar chapas ni piezas brutas<\/li>\n\n\n\n<li>Tama\u00f1o limitado por la anchura m\u00e1xima de bobina que se puede manipular<\/li>\n\n\n\n<li>Ajustes necesarios al cambiar el grosor y el grado del material<\/li>\n\n\n\n<li>Profesionales necesarios para el funcionamiento, el mantenimiento y las reparaciones<\/li>\n\n\n\n<li>Requieren un proceso de perforaci\u00f3n independiente para perforar agujeros<\/li>\n\n\n\n<li>No apto para peque\u00f1os fabricantes<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Desaf\u00edos<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Tolerancia de los perfiles y alineaci\u00f3n de los orificios seg\u00fan las normas<\/li>\n\n\n\n<li>Resoluci\u00f3n de aver\u00edas e interrupciones de la l\u00ednea<\/li>\n\n\n\n<li>Gesti\u00f3n de cambios r\u00e1pidos entre distintos perfiles<\/li>\n\n\n\n<li>Manipulaci\u00f3n de bobinas sin da\u00f1os en la superficie ni restos de cinta adhesiva<\/li>\n\n\n\n<li>Mantenimiento de la forma constante en largas series de producci\u00f3n<\/li>\n\n\n\n<li>Formaci\u00f3n de los operarios para un funcionamiento \u00f3ptimo de la l\u00ednea<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">La automatizaci\u00f3n y el control de calidad de precisi\u00f3n en cada etapa son necesarios para superar estas limitaciones.<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><img decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/swforming.com\/wp-content\/uploads\/2023\/07\/Hydraulic-Roof-Sheet-Curving-Machine-04.webp\" alt=\"m\u00e1quina perfiladora de esp\u00e1rragos y rieles\" class=\"wp-image-3586\" title=\"\" srcset=\"https:\/\/swforming.com\/wp-content\/uploads\/2023\/07\/Hydraulic-Roof-Sheet-Curving-Machine-04.webp 800w, https:\/\/swforming.com\/wp-content\/uploads\/2023\/07\/Hydraulic-Roof-Sheet-Curving-Machine-04-400x400.webp 400w, https:\/\/swforming.com\/wp-content\/uploads\/2023\/07\/Hydraulic-Roof-Sheet-Curving-Machine-04-100x100.webp 100w, https:\/\/swforming.com\/wp-content\/uploads\/2023\/07\/Hydraulic-Roof-Sheet-Curving-Machine-04-600x600.webp 600w, https:\/\/swforming.com\/wp-content\/uploads\/2023\/07\/Hydraulic-Roof-Sheet-Curving-Machine-04-300x300.webp 300w, https:\/\/swforming.com\/wp-content\/uploads\/2023\/07\/Hydraulic-Roof-Sheet-Curving-Machine-04-150x150.webp 150w, https:\/\/swforming.com\/wp-content\/uploads\/2023\/07\/Hydraulic-Roof-Sheet-Curving-Machine-04-768x768.webp 768w, https:\/\/swforming.com\/wp-content\/uploads\/2023\/07\/Hydraulic-Roof-Sheet-Curving-Machine-04-12x12.webp 12w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><figcaption><\/figcaption><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">Elegir entre el perfilado y la fabricaci\u00f3n de montantes\/racks<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">El perfilado y la fabricaci\u00f3n son los dos m\u00e9todos principales de producci\u00f3n de esp\u00e1rragos y ra\u00edles. He aqu\u00ed una comparaci\u00f3n entre el laminado y la fabricaci\u00f3n:<\/p>\n\n\n\n<figure class=\"wp-block-table\"><table><thead><tr><th><strong>Par\u00e1metro<\/strong><\/th><th><strong>Perfilado<\/strong><\/th><th><strong>Fabricaci\u00f3n<\/strong><\/th><\/tr><\/thead><tbody><tr><td>Proceso<\/td><td>Conformado en fr\u00edo mediante estaciones de rodillos progresivos<\/td><td>Corte de secciones de chapas y fabricaci\u00f3n de estructuras<\/td><\/tr><tr><td>Tiempo de preparaci\u00f3n<\/td><td>Bajo con cambios r\u00e1pidos<\/td><td>Alta con m\u00faltiples procesos<\/td><\/tr><tr><td>Duraci\u00f3n del ciclo<\/td><td>Muy bajo debido al funcionamiento continuo<\/td><td>Mayor debido a la naturaleza del lote<\/td><\/tr><tr><td>Trabajo<\/td><td>Menor debido a la automatizaci\u00f3n<\/td><td>Mayor debido a los procesos manuales<\/td><\/tr><tr><td>Tasa de salida<\/td><td>Muy alto, hasta 100 m\/min<\/td><td>Bajo 10-20 m\/min<\/td><\/tr><tr><td>Calidad<\/td><td>Consistente, buenas tolerancias<\/td><td>Variable, depende de la habilidad del operario<\/td><\/tr><tr><td>Trabajo secundario<\/td><td>Requiere un acabado m\u00ednimo<\/td><td>Es necesario fresar, rectificar y perforar<\/td><\/tr><tr><td>Costo<\/td><td>Menor debido a la alta productividad, baja mano de obra<\/td><td>Mayor debido a los m\u00faltiples procesos<\/td><\/tr><tr><td>Flexibilidad<\/td><td>Limitado a los perfiles que pueden hacer los rodillos<\/td><td>Muy alto, se puede fabricar cualquier forma<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Consideraciones clave:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Perfilado \u00f3ptimo para series largas y continuas<\/li>\n\n\n\n<li>Fabricaci\u00f3n adecuada para vol\u00famenes reducidos o perfiles personalizados que no son posibles mediante perfilado<\/li>\n\n\n\n<li>El perfilado tiene una entrega m\u00e1s r\u00e1pida con un trabajo de acabado m\u00ednimo<\/li>\n\n\n\n<li>La fabricaci\u00f3n requiere trabajadores cualificados para garantizar la calidad y la uniformidad.<\/li>\n\n\n\n<li>Los travesa\u00f1os y ra\u00edles perfilados ofrecen un rendimiento estructural superior<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Para grandes series de producci\u00f3n, el perfilado es el proceso preferido por su rapidez, calidad y rentabilidad. Pero la fabricaci\u00f3n ofrece la flexibilidad de forma necesaria para los perfiles personalizados.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Preguntas m\u00e1s frecuentes<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">P: \u00bfCu\u00e1l es el ritmo habitual de producci\u00f3n de clavos y orugas?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">R: Las velocidades de producci\u00f3n var\u00edan entre 60 y 100 metros por minuto en funci\u00f3n de la velocidad de la m\u00e1quina, el grosor de hasta 3 mm y la complejidad del perfil. Las l\u00edneas totalmente autom\u00e1ticas pueden producir hasta 100 m\/min.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">P: \u00bfQu\u00e9 grosor de bobina se puede laminar?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">R: El grosor de las bobinas oscila entre 0,5 mm y 3 mm. El l\u00edmite el\u00e1stico suele rondar los 550 MPa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">P: \u00bfQu\u00e9 formas distintas de la C y la U se pueden formar?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">R: Las avanzadas l\u00edneas de perfilado pueden producir perfiles en L, Z, C, Omega y formas personalizadas. Tambi\u00e9n es posible fabricar perfiles en forma de sombrero.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">P: \u00bfQu\u00e9 motores se utilizan para accionar la perfiladora?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">R: Las l\u00edneas de esp\u00e1rragos y v\u00edas utilizan predominantemente servomotores de CA que permiten un control preciso de la velocidad de cada estaci\u00f3n de rodillos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">P: \u00bfCu\u00e1les son las necesidades t\u00edpicas de mantenimiento?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">R: Inspecci\u00f3n de rodillos, lubricaci\u00f3n, comprobaciones de sistemas hidr\u00e1ulicos\/neum\u00e1ticos, apriete de tornillos, sustituci\u00f3n de rodillos cuando est\u00e9n desgastados.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">P: \u00bfC\u00f3mo de r\u00e1pidos son los cambios entre distintos perfiles?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">R: En las l\u00edneas combinadas, los cambios tardan entre 15 y 30 minutos, dependiendo del n\u00famero de rollos que haya que cambiar. Las m\u00e1quinas de perfil fijo tienen tiempos de cambio m\u00e1s largos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">P: \u00bfCu\u00e1l es la disposici\u00f3n t\u00edpica de una l\u00ednea?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">R: Comienza con el desenrollador, seguido de la unidad de alimentaci\u00f3n, la secci\u00f3n de despiece, el prepunzonado si es necesario, los soportes de acabado, la prensa de corte y, por \u00faltimo, el apilador.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">P: \u00bfQu\u00e9 tipo de formaci\u00f3n se necesita para manejar estas m\u00e1quinas?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">R: Se recomienda que los t\u00e9cnicos reciban una formaci\u00f3n exhaustiva en el aula y en el puesto de trabajo. Los operarios necesitan formaci\u00f3n sobre la configuraci\u00f3n, el funcionamiento, la seguridad y el mantenimiento de la m\u00e1quina.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">P: \u00bfQu\u00e9 factores afectan al precio total de la l\u00ednea de perfilado?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">R: La velocidad, la capacidad de manipulaci\u00f3n del tama\u00f1o de la bobina, las funciones de automatizaci\u00f3n, el dise\u00f1o del cambio y los accesorios opcionales influyen en el precio. La marca y la ubicaci\u00f3n influyen en el precio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">P: \u00bfCu\u00e1les son las aplicaciones finales de los tacos y ra\u00edles?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">R: Las principales aplicaciones son los entramados de muros, muros cortina, entreplantas, cerchas y rejillas de techos suspendidos. Forman el esqueleto estructural de los edificios.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/en.wikipedia.org\/wiki\/Roll_forming\" target=\"_blank\" rel=\"noreferrer noopener\">saber m\u00e1s Perfilado<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>Roll forming is a metal working process in which sheet metal is gradually bent into a desired cross-sectional profile through a series of roll stations. Stud and track roll forming machines are used to form studs and tracks from coiled steel which are used in wall framing and curtain wall systems in the construction industry. [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":3495,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[1],"tags":[],"class_list":["post-4162","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":7}},"acf":[],"_links":{"self":[{"href":"https:\/\/swforming.com\/es\/wp-json\/wp\/v2\/posts\/4162","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/swforming.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/swforming.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/swforming.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/swforming.com\/es\/wp-json\/wp\/v2\/comments?post=4162"}],"version-history":[{"count":1,"href":"https:\/\/swforming.com\/es\/wp-json\/wp\/v2\/posts\/4162\/revisions"}],"predecessor-version":[{"id":4163,"href":"https:\/\/swforming.com\/es\/wp-json\/wp\/v2\/posts\/4162\/revisions\/4163"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/swforming.com\/es\/wp-json\/wp\/v2\/media\/3495"}],"wp:attachment":[{"href":"https:\/\/swforming.com\/es\/wp-json\/wp\/v2\/media?parent=4162"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/swforming.com\/es\/wp-json\/wp\/v2\/categories?post=4162"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/swforming.com\/es\/wp-json\/wp\/v2\/tags?post=4162"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}